{"id":279046,"count":11,"description":"","link":"https:\/\/beautysuppliers.org\/wm-good\/category\/cookies-chips\/nuts\/","name":"Nuts","slug":"nuts","taxonomy":"product_cat","parent":263454,"meta":[],"_links":{"self":[{"href":"https:\/\/beautysuppliers.org\/wm-good\/wp-json\/wp\/v2\/product_cat\/279046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beautysuppliers.org\/wm-good\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/beautysuppliers.org\/wm-good\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/beautysuppliers.org\/wm-good\/wp-json\/wp\/v2\/product_cat\/263454"}],"wp:post_type":[{"href":"https:\/\/beautysuppliers.org\/wm-good\/wp-json\/wp\/v2\/product?product_cat=279046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}